{"id":1261,"date":"2022-09-01T09:43:42","date_gmt":"2022-09-01T07:43:42","guid":{"rendered":"https:\/\/comunita-ellenica.ch\/?p=1261"},"modified":"2022-09-01T09:43:42","modified_gmt":"2022-09-01T07:43:42","slug":"assemblea-generale-ordinaria","status":"publish","type":"post","link":"https:\/\/comunita-ellenica.ch\/it\/2022\/09\/01\/assemblea-generale-ordinaria\/","title":{"rendered":"CONVOCAZIONE DELL\u2019ASSEMBLEA GENERALE ORDINARIA"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Cari Membri,<\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">L'Assemblea Generale Ordinaria della Comunit\u00e0 sar\u00e0 convocata <strong>domenica 11 settembre 2022, alle ore 16:00<\/strong>, presso il vecchio municipio di Castagnola (Piazza Carlo Cattaneo 1, 6976 Castagnola) con le seguenti trattande:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Rendiconto dell\u2019attivit\u00e0 del Consiglio Direttivo uscente;<\/li><li>Rendiconto finanziario;<\/li><li>Elezione del presidente del giorno e dei due scrutatori;<\/li><li>Elezione del nuovo Consiglio Direttivo e del nuovo Collegio dei Revisori.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">Le candidature per il nuovo Consiglio Direttivo devono essere presentate per iscritto entro il 4 settembre 2022 all'indirizzo e-mail della Comunit\u00e0 <a href=\"mailto:info@comunita-ellenica.ch\" target=\"_self\">info@comunita-ellenica.ch<\/a> o all'indirizzo postale della Comunit\u00e0, Comunit\u00e0 Ellenica del Cantone Ticino, Casella Postale 1902, CH-6901 Lugano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ai sensi dell\u2019Articolo 8 dello Statuto della Comunit\u00e0, l\u2019Assemblea Generale Ordinaria ha numero legale quando sono presenti la met\u00e0 pi\u00f9 uno dei membri in regola con il pagamento della quota sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel caso in cui il numero legale non venisse raggiunto, l\u2019Assemblea Generale Ordinaria si rimanda di una settimana, senza nuova comunicazione scritta, con lo stesso ordine del giorno, alla stessa ora e nello stesso luogo, i.e. domenica 18 settembre 2022 alle ore 16:00 presso il vecchio municipio di Castagnola (Piazza Carlo Cattaneo 1, 6976 Castagnola).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa nuova Assemblea Generale avr\u00e0 numero legale, indipendentemente dal numero dei membri presenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cordiali saluti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Presidente e i membri del Consiglio Direttivo<\/p>","protected":false},"excerpt":{"rendered":"<p>Cari Membri, L'Assemblea Generale Ordinaria della Comunit\u00e0 sar\u00e0 convocata domenica 11 settembre 2022, alle ore 16:00, presso il vecchio municipio di Castagnola (Piazza Carlo Cattaneo 1, 6976 Castagnola) con le seguenti trattande: Rendiconto dell\u2019attivit\u00e0 del Consiglio Direttivo uscente; Rendiconto... <\/p>\n<p class=\"more-link-container th-uppercase th-text-2xs\"><a href=\"https:\/\/comunita-ellenica.ch\/it\/2022\/09\/01\/assemblea-generale-ordinaria\/\" class=\"more-link\">Read More <span class=\"screen-reader-text\">CONVOCAZIONE DELL\u2019ASSEMBLEA GENERALE ORDINARIA<\/span><\/a><\/p>","protected":false},"author":111599291,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8436094],"tags":[],"class_list":["post-1261","post","type-post","status-publish","format-standard","hentry","category-8436094"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcLJfg-kl","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/posts\/1261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/users\/111599291"}],"replies":[{"embeddable":true,"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/comments?post=1261"}],"version-history":[{"count":3,"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/posts\/1261\/revisions"}],"predecessor-version":[{"id":1265,"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/posts\/1261\/revisions\/1265"}],"wp:attachment":[{"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/media?parent=1261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/categories?post=1261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunita-ellenica.ch\/it\/wp-json\/wp\/v2\/tags?post=1261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}